{"id":109,"count":2,"description":"","link":"https:\/\/www.dent.psu.ac.th\/dent\/category\/sdg17\/","name":"SDG17","slug":"sdg17","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SDG17 Archives - \u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dent.psu.ac.th\/dent\/category\/sdg17\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SDG17 Archives - \u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dent.psu.ac.th\/dent\/category\/sdg17\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.dent.psu.ac.th\/dent\/category\/sdg17\/\",\"url\":\"https:\/\/www.dent.psu.ac.th\/dent\/category\/sdg17\/\",\"name\":\"SDG17 Archives - \u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\",\"isPartOf\":{\"@id\":\"https:\/\/www.dent.psu.ac.th\/dent\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.dent.psu.ac.th\/dent\/category\/sdg17\/#breadcrumb\"},\"inLanguage\":\"th\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.dent.psu.ac.th\/dent\/category\/sdg17\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.dent.psu.ac.th\/dent\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SDG17\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.dent.psu.ac.th\/dent\/#website\",\"url\":\"https:\/\/www.dent.psu.ac.th\/dent\/\",\"name\":\"\u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\",\"description\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\",\"publisher\":{\"@id\":\"https:\/\/www.dent.psu.ac.th\/dent\/#organization\"},\"alternateName\":\"Dent PSU\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.dent.psu.ac.th\/dent\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.dent.psu.ac.th\/dent\/#organization\",\"name\":\"\u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\",\"alternateName\":\"Dent PSU\",\"url\":\"https:\/\/www.dent.psu.ac.th\/dent\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/www.dent.psu.ac.th\/dent\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.dent.psu.ac.th\/dent\/wp-content\/uploads\/2020\/09\/logo_short_v_en.png\",\"contentUrl\":\"https:\/\/www.dent.psu.ac.th\/dent\/wp-content\/uploads\/2020\/09\/logo_short_v_en.png\",\"width\":960,\"height\":800,\"caption\":\"\u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\"},\"image\":{\"@id\":\"https:\/\/www.dent.psu.ac.th\/dent\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/DentPSU\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SDG17 Archives - \u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dent.psu.ac.th\/dent\/category\/sdg17\/","og_locale":"th_TH","og_type":"article","og_title":"SDG17 Archives - \u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c","og_url":"https:\/\/www.dent.psu.ac.th\/dent\/category\/sdg17\/","og_site_name":"\u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.dent.psu.ac.th\/dent\/category\/sdg17\/","url":"https:\/\/www.dent.psu.ac.th\/dent\/category\/sdg17\/","name":"SDG17 Archives - \u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c","isPartOf":{"@id":"https:\/\/www.dent.psu.ac.th\/dent\/#website"},"breadcrumb":{"@id":"https:\/\/www.dent.psu.ac.th\/dent\/category\/sdg17\/#breadcrumb"},"inLanguage":"th"},{"@type":"BreadcrumbList","@id":"https:\/\/www.dent.psu.ac.th\/dent\/category\/sdg17\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.dent.psu.ac.th\/dent\/"},{"@type":"ListItem","position":2,"name":"SDG17"}]},{"@type":"WebSite","@id":"https:\/\/www.dent.psu.ac.th\/dent\/#website","url":"https:\/\/www.dent.psu.ac.th\/dent\/","name":"\u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c","description":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c","publisher":{"@id":"https:\/\/www.dent.psu.ac.th\/dent\/#organization"},"alternateName":"Dent PSU","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dent.psu.ac.th\/dent\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/www.dent.psu.ac.th\/dent\/#organization","name":"\u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c","alternateName":"Dent PSU","url":"https:\/\/www.dent.psu.ac.th\/dent\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.dent.psu.ac.th\/dent\/#\/schema\/logo\/image\/","url":"https:\/\/www.dent.psu.ac.th\/dent\/wp-content\/uploads\/2020\/09\/logo_short_v_en.png","contentUrl":"https:\/\/www.dent.psu.ac.th\/dent\/wp-content\/uploads\/2020\/09\/logo_short_v_en.png","width":960,"height":800,"caption":"\u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c"},"image":{"@id":"https:\/\/www.dent.psu.ac.th\/dent\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DentPSU\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.dent.psu.ac.th\/dent\/wp-json\/wp\/v2\/categories\/109"}],"collection":[{"href":"https:\/\/www.dent.psu.ac.th\/dent\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.dent.psu.ac.th\/dent\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.dent.psu.ac.th\/dent\/wp-json\/wp\/v2\/posts?categories=109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}