{"id":10979,"date":"2026-05-29T08:39:09","date_gmt":"2026-05-29T01:39:09","guid":{"rendered":"https:\/\/www.dent.psu.ac.th\/dent\/?p=10979"},"modified":"2026-05-29T08:40:30","modified_gmt":"2026-05-29T01:40:30","slug":"%e0%b8%82%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b9%80%e0%b8%a7%e0%b8%a5%e0%b8%b2%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%aa%e0%b8%a1%e0%b8%b1%e0%b8%84%e0%b8%a3%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%88%e0%b8%b3%e0%b8%ab","status":"publish","type":"post","link":"https:\/\/www.dent.psu.ac.th\/dent\/%e0%b8%82%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b9%80%e0%b8%a7%e0%b8%a5%e0%b8%b2%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%aa%e0%b8%a1%e0%b8%b1%e0%b8%84%e0%b8%a3%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%88%e0%b8%b3%e0%b8%ab\/","title":{"rendered":"\u0e02\u0e22\u0e32\u0e22\u0e40\u0e27\u0e25\u0e32\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e42\u0e23\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e0a\u0e31\u0e49\u0e19 G \u0e2d\u0e32\u0e04\u0e32\u0e23 1\u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2569"},"content":{"rendered":"\n<p class=\"has-text-align-center\">\u0e14\u0e49\u0e27\u0e22\u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e08\u0e30\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23<br>\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e40\u0e0a\u0e48\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e23\u0e49\u0e32\u0e19 \u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13 \u0e0a\u0e31\u0e49\u0e19 G \u0e2d\u0e32\u0e04\u0e32\u0e23 1 \u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49<br><\/p>\n\n\n\n<div class=\"wp-block-uagb-image aligncenter uagb-block-4ba2c59f wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-center\"><figure class=\"wp-block-uagb-image__figure\"><img loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.dent.psu.ac.th\/dent\/wp-content\/uploads\/2026\/05\/\u0e02\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e15\u0e25\u0e32\u0e14\u0e1e\u0e31\u0e2a\u0e14\u0e38\u0e38-2.jpg ,https:\/\/www.dent.psu.ac.th\/dent\/wp-content\/uploads\/2026\/05\/\u0e02\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e15\u0e25\u0e32\u0e14\u0e1e\u0e31\u0e2a\u0e14\u0e38\u0e38-2.jpg 780w, https:\/\/www.dent.psu.ac.th\/dent\/wp-content\/uploads\/2026\/05\/\u0e02\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e15\u0e25\u0e32\u0e14\u0e1e\u0e31\u0e2a\u0e14\u0e38\u0e38-2.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"https:\/\/www.dent.psu.ac.th\/dent\/wp-content\/uploads\/2026\/05\/\u0e02\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e15\u0e25\u0e32\u0e14\u0e1e\u0e31\u0e2a\u0e14\u0e38\u0e38-2.jpg\" alt=\"\" class=\"uag-image-10980\" width=\"2160\" height=\"1080\" title=\"\u0e02\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e15\u0e25\u0e32\u0e14\u0e1e\u0e31\u0e2a\u0e14\u0e38\u0e38 (2)\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n\n\n\n<ul>\n<li><strong><mark>\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e02\u0e2d\u0e07\u0e23\u0e49\u0e32\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23<\/mark><\/strong><\/li>\n<\/ul>\n\n\n\n<p>\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34\/\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e27\u0e48\u0e32\u0e07 \u0e2d\u0e31\u0e15\u0e23\u0e32\u0e04\u0e48\u0e32\u0e40\u0e0a\u0e48\u0e32 3,000 \u0e1a\u0e32\u0e17\u0e15\u0e48\u0e2d\u0e40\u0e14\u0e37\u0e2d\u0e19<\/p>\n\n\n\n<ul>\n<li><strong><mark>\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e41\u0e25\u0e30\u0e04\u0e48\u0e32\u0e2a\u0e21\u0e31\u0e04\u0e23<\/mark><\/strong><\/li>\n<\/ul>\n\n\n\n<p>\u0e40\u0e1b\u0e34\u0e14\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e1a\u0e31\u0e14\u0e19\u0e35\u0e49 \u0e08\u0e19\u0e16\u0e36\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 <strong>8 \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 \u0e1e.\u0e28. 2569<\/strong>\u00a0\u0e42\u0e14\u0e22\u0e21\u0e35\u0e04\u0e48\u0e32\u0e2a\u0e21\u0e31\u0e04\u0e23 \u0e08\u0e33\u0e19\u0e27\u0e19\u00a0<strong>200 \u0e1a\u0e32\u0e17<\/strong><\/p>\n\n\n\n<ul>\n<li><strong><mark>\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e21\u0e31\u0e04\u0e23<\/mark><\/strong><\/li>\n<\/ul>\n\n\n\n<p>\u0e1c\u0e39\u0e49\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e15\u0e49\u0e2d\u0e07\u0e22\u0e37\u0e48\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e41\u0e19\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e19\u0e35\u0e49<\/p>\n\n\n\n<ul>\n<li><strong><mark>\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01<\/mark><\/strong><\/li>\n<\/ul>\n\n\n\n<p>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48\u00a0<strong><em>9 \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 \u0e1e.\u0e28. 2569<\/em><\/strong><\/p>\n\n\n\n<ul>\n<li><strong><mark>\u0e27\u0e31\u0e19 \u0e40\u0e27\u0e25\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01<\/mark><\/strong><\/li>\n<\/ul>\n\n\n\n<p>\u0e1c\u0e39\u0e49\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d\u0e15\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28 \u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e43\u0e19<strong>\u0e27\u0e31\u0e19\u0e1e\u0e24\u0e2b\u0e31\u0e2a\u0e1a\u0e14\u0e35 \u0e17\u0e35\u0e48 11 \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19  \u0e1e.\u0e28. 2569<\/strong>\u00a0\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e40\u0e27\u0e25\u0e32\u00a0<strong>11.00 \u0e19. \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19\u0e44\u0e1b<\/strong>\u00a0\u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 5 \u0e0a\u0e31\u0e49\u0e19 7 \u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e2b\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e23\u0e32\u0e22\u0e43\u0e14\u0e44\u0e21\u0e48\u0e21\u0e32 \u0e43\u0e2b\u0e49\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e2a\u0e25\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c<\/p>\n\n\n\n<ul>\n<li><strong><mark>\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01<\/mark><\/strong><\/li>\n<\/ul>\n\n\n\n<p>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01 \u0e20\u0e32\u0e22\u0e43\u0e19<strong>\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 15 \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 \u0e1e.\u0e28. 2569<\/strong><\/p>\n\n\n\n<ul>\n<li><strong><mark>\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01<\/mark><\/strong><\/li>\n<\/ul>\n\n\n\n<p>\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e40\u0e0a\u0e48\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48<strong> \u0e20\u0e32\u0e22\u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 22-26 \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 \u0e1e.\u0e28. 2569<\/strong>\u00a0\u0e2b\u0e32\u0e01\u0e44\u0e21\u0e48\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e20\u0e32\u0e22\u0e43\u0e19\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14 \u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e2a\u0e25\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e41\u0e25\u0e30\u0e08\u0e30<strong>\u0e15\u0e49\u0e2d\u0e07\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 1 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2569<\/strong><\/p>\n\n\n\n<p>\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e2a\u0e19\u0e43\u0e08\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e28\u0e36\u0e01\u0e29\u0e32\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e25\u0e48\u0e32\u0e07\u00a0\u0e41\u0e25\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e43\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u00a0<strong>\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 7 \u0e02\u0e2d\u0e07\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23<\/strong>\u00a0\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 074-287519 (\u0e04\u0e38\u0e13\u0e2d\u0e38\u0e29\u0e32) \u0e41\u0e25\u0e30 074-287526 (\u0e04\u0e38\u0e13\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e27\u0e31\u0e25\u0e22\u0e4c)<\/p>\n\n\n<a href=\"https:\/\/www.dent.psu.ac.th\/dent\/wp-content\/uploads\/2026\/05\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c-\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"bottom\" data-toolbar-fixed=\"off\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c-\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25<\/a>","protected":false},"excerpt":{"rendered":"<p>\u0e14\u0e49\u0e27\u0e22\u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e23 [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":10980,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[101,117,68,33],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e02\u0e22\u0e32\u0e22\u0e40\u0e27\u0e25\u0e32\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e42\u0e23\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e0a\u0e31\u0e49\u0e19 G \u0e2d\u0e32\u0e04\u0e32\u0e23 1\u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2569 - \u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dent.psu.ac.th\/dent\/\u0e02\u0e22\u0e32\u0e22\u0e40\u0e27\u0e25\u0e32\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e33\u0e2b\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e02\u0e22\u0e32\u0e22\u0e40\u0e27\u0e25\u0e32\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e42\u0e23\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e0a\u0e31\u0e49\u0e19 G \u0e2d\u0e32\u0e04\u0e32\u0e23 1\u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2569 - \u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\" \/>\n<meta property=\"og:description\" content=\"\u0e14\u0e49\u0e27\u0e22\u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e23 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dent.psu.ac.th\/dent\/\u0e02\u0e22\u0e32\u0e22\u0e40\u0e27\u0e25\u0e32\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e33\u0e2b\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DentPSU\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-29T01:39:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-29T01:40:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dent.psu.ac.th\/dent\/wp-content\/uploads\/2026\/05\/\u0e02\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e15\u0e25\u0e32\u0e14\u0e1e\u0e31\u0e2a\u0e14\u0e38\u0e38-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2160\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jaruwan damsyum\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jaruwan damsyum\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.dent.psu.ac.th\/dent\/%e0%b8%82%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b9%80%e0%b8%a7%e0%b8%a5%e0%b8%b2%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%aa%e0%b8%a1%e0%b8%b1%e0%b8%84%e0%b8%a3%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%88%e0%b8%b3%e0%b8%ab\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.dent.psu.ac.th\/dent\/%e0%b8%82%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b9%80%e0%b8%a7%e0%b8%a5%e0%b8%b2%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%aa%e0%b8%a1%e0%b8%b1%e0%b8%84%e0%b8%a3%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%88%e0%b8%b3%e0%b8%ab\/\"},\"author\":{\"name\":\"Jaruwan damsyum\",\"@id\":\"https:\/\/www.dent.psu.ac.th\/dent\/#\/schema\/person\/069e8a0892876674876f8ba63c466988\"},\"headline\":\"\u0e02\u0e22\u0e32\u0e22\u0e40\u0e27\u0e25\u0e32\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e42\u0e23\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e0a\u0e31\u0e49\u0e19 G \u0e2d\u0e32\u0e04\u0e32\u0e23 1\u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2569\",\"datePublished\":\"2026-05-29T01:39:09+00:00\",\"dateModified\":\"2026-05-29T01:40:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.dent.psu.ac.th\/dent\/%e0%b8%82%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b9%80%e0%b8%a7%e0%b8%a5%e0%b8%b2%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%aa%e0%b8%a1%e0%b8%b1%e0%b8%84%e0%b8%a3%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%88%e0%b8%b3%e0%b8%ab\/\"},\"wordCount\":5,\"publisher\":{\"@id\":\"https:\/\/www.dent.psu.ac.th\/dent\/#organization\"},\"articleSection\":[\"SDG1\",\"SDG2\",\"\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19\",\"\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\"],\"inLanguage\":\"th\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.dent.psu.ac.th\/dent\/%e0%b8%82%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b9%80%e0%b8%a7%e0%b8%a5%e0%b8%b2%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%aa%e0%b8%a1%e0%b8%b1%e0%b8%84%e0%b8%a3%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%88%e0%b8%b3%e0%b8%ab\/\",\"url\":\"https:\/\/www.dent.psu.ac.th\/dent\/%e0%b8%82%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b9%80%e0%b8%a7%e0%b8%a5%e0%b8%b2%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%aa%e0%b8%a1%e0%b8%b1%e0%b8%84%e0%b8%a3%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%88%e0%b8%b3%e0%b8%ab\/\",\"name\":\"\u0e02\u0e22\u0e32\u0e22\u0e40\u0e27\u0e25\u0e32\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e42\u0e23\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e0a\u0e31\u0e49\u0e19 G \u0e2d\u0e32\u0e04\u0e32\u0e23 1\u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2569 - \u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\",\"isPartOf\":{\"@id\":\"https:\/\/www.dent.psu.ac.th\/dent\/#website\"},\"datePublished\":\"2026-05-29T01:39:09+00:00\",\"dateModified\":\"2026-05-29T01:40:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.dent.psu.ac.th\/dent\/%e0%b8%82%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b9%80%e0%b8%a7%e0%b8%a5%e0%b8%b2%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%aa%e0%b8%a1%e0%b8%b1%e0%b8%84%e0%b8%a3%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%88%e0%b8%b3%e0%b8%ab\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.dent.psu.ac.th\/dent\/%e0%b8%82%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b9%80%e0%b8%a7%e0%b8%a5%e0%b8%b2%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%aa%e0%b8%a1%e0%b8%b1%e0%b8%84%e0%b8%a3%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%88%e0%b8%b3%e0%b8%ab\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.dent.psu.ac.th\/dent\/%e0%b8%82%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b9%80%e0%b8%a7%e0%b8%a5%e0%b8%b2%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%aa%e0%b8%a1%e0%b8%b1%e0%b8%84%e0%b8%a3%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%88%e0%b8%b3%e0%b8%ab\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.dent.psu.ac.th\/dent\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e02\u0e22\u0e32\u0e22\u0e40\u0e27\u0e25\u0e32\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e42\u0e23\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e0a\u0e31\u0e49\u0e19 G \u0e2d\u0e32\u0e04\u0e32\u0e23 1\u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2569\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.dent.psu.ac.th\/dent\/#website\",\"url\":\"https:\/\/www.dent.psu.ac.th\/dent\/\",\"name\":\"\u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\",\"description\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\",\"publisher\":{\"@id\":\"https:\/\/www.dent.psu.ac.th\/dent\/#organization\"},\"alternateName\":\"Dent PSU\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.dent.psu.ac.th\/dent\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.dent.psu.ac.th\/dent\/#organization\",\"name\":\"\u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\",\"alternateName\":\"Dent PSU\",\"url\":\"https:\/\/www.dent.psu.ac.th\/dent\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/www.dent.psu.ac.th\/dent\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.dent.psu.ac.th\/dent\/wp-content\/uploads\/2020\/09\/logo_short_v_en.png\",\"contentUrl\":\"https:\/\/www.dent.psu.ac.th\/dent\/wp-content\/uploads\/2020\/09\/logo_short_v_en.png\",\"width\":960,\"height\":800,\"caption\":\"\u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\"},\"image\":{\"@id\":\"https:\/\/www.dent.psu.ac.th\/dent\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/DentPSU\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.dent.psu.ac.th\/dent\/#\/schema\/person\/069e8a0892876674876f8ba63c466988\",\"name\":\"Jaruwan damsyum\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/www.dent.psu.ac.th\/dent\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/208d4c5a44e4da86a40f61d8dfa10656?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/208d4c5a44e4da86a40f61d8dfa10656?s=96&d=mm&r=g\",\"caption\":\"Jaruwan damsyum\"},\"url\":\"https:\/\/www.dent.psu.ac.th\/dent\/author\/jaruwan-d\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e02\u0e22\u0e32\u0e22\u0e40\u0e27\u0e25\u0e32\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e42\u0e23\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e0a\u0e31\u0e49\u0e19 G \u0e2d\u0e32\u0e04\u0e32\u0e23 1\u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2569 - \u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dent.psu.ac.th\/dent\/\u0e02\u0e22\u0e32\u0e22\u0e40\u0e27\u0e25\u0e32\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e33\u0e2b\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e02\u0e22\u0e32\u0e22\u0e40\u0e27\u0e25\u0e32\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e42\u0e23\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e0a\u0e31\u0e49\u0e19 G \u0e2d\u0e32\u0e04\u0e32\u0e23 1\u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2569 - \u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c","og_description":"\u0e14\u0e49\u0e27\u0e22\u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e23 [&hellip;]","og_url":"https:\/\/www.dent.psu.ac.th\/dent\/\u0e02\u0e22\u0e32\u0e22\u0e40\u0e27\u0e25\u0e32\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e33\u0e2b\/","og_site_name":"\u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c","article_publisher":"https:\/\/www.facebook.com\/DentPSU\/","article_published_time":"2026-05-29T01:39:09+00:00","article_modified_time":"2026-05-29T01:40:30+00:00","og_image":[{"width":2160,"height":1080,"url":"https:\/\/www.dent.psu.ac.th\/dent\/wp-content\/uploads\/2026\/05\/\u0e02\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e15\u0e25\u0e32\u0e14\u0e1e\u0e31\u0e2a\u0e14\u0e38\u0e38-2.jpg","type":"image\/jpeg"}],"author":"Jaruwan damsyum","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jaruwan damsyum","Est. reading time":"1 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.dent.psu.ac.th\/dent\/%e0%b8%82%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b9%80%e0%b8%a7%e0%b8%a5%e0%b8%b2%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%aa%e0%b8%a1%e0%b8%b1%e0%b8%84%e0%b8%a3%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%88%e0%b8%b3%e0%b8%ab\/#article","isPartOf":{"@id":"https:\/\/www.dent.psu.ac.th\/dent\/%e0%b8%82%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b9%80%e0%b8%a7%e0%b8%a5%e0%b8%b2%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%aa%e0%b8%a1%e0%b8%b1%e0%b8%84%e0%b8%a3%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%88%e0%b8%b3%e0%b8%ab\/"},"author":{"name":"Jaruwan damsyum","@id":"https:\/\/www.dent.psu.ac.th\/dent\/#\/schema\/person\/069e8a0892876674876f8ba63c466988"},"headline":"\u0e02\u0e22\u0e32\u0e22\u0e40\u0e27\u0e25\u0e32\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e42\u0e23\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e0a\u0e31\u0e49\u0e19 G \u0e2d\u0e32\u0e04\u0e32\u0e23 1\u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2569","datePublished":"2026-05-29T01:39:09+00:00","dateModified":"2026-05-29T01:40:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.dent.psu.ac.th\/dent\/%e0%b8%82%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b9%80%e0%b8%a7%e0%b8%a5%e0%b8%b2%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%aa%e0%b8%a1%e0%b8%b1%e0%b8%84%e0%b8%a3%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%88%e0%b8%b3%e0%b8%ab\/"},"wordCount":5,"publisher":{"@id":"https:\/\/www.dent.psu.ac.th\/dent\/#organization"},"articleSection":["SDG1","SDG2","\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19","\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23"],"inLanguage":"th"},{"@type":"WebPage","@id":"https:\/\/www.dent.psu.ac.th\/dent\/%e0%b8%82%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b9%80%e0%b8%a7%e0%b8%a5%e0%b8%b2%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%aa%e0%b8%a1%e0%b8%b1%e0%b8%84%e0%b8%a3%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%88%e0%b8%b3%e0%b8%ab\/","url":"https:\/\/www.dent.psu.ac.th\/dent\/%e0%b8%82%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b9%80%e0%b8%a7%e0%b8%a5%e0%b8%b2%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%aa%e0%b8%a1%e0%b8%b1%e0%b8%84%e0%b8%a3%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%88%e0%b8%b3%e0%b8%ab\/","name":"\u0e02\u0e22\u0e32\u0e22\u0e40\u0e27\u0e25\u0e32\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e42\u0e23\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e0a\u0e31\u0e49\u0e19 G \u0e2d\u0e32\u0e04\u0e32\u0e23 1\u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2569 - \u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c","isPartOf":{"@id":"https:\/\/www.dent.psu.ac.th\/dent\/#website"},"datePublished":"2026-05-29T01:39:09+00:00","dateModified":"2026-05-29T01:40:30+00:00","breadcrumb":{"@id":"https:\/\/www.dent.psu.ac.th\/dent\/%e0%b8%82%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b9%80%e0%b8%a7%e0%b8%a5%e0%b8%b2%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%aa%e0%b8%a1%e0%b8%b1%e0%b8%84%e0%b8%a3%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%88%e0%b8%b3%e0%b8%ab\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dent.psu.ac.th\/dent\/%e0%b8%82%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b9%80%e0%b8%a7%e0%b8%a5%e0%b8%b2%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%aa%e0%b8%a1%e0%b8%b1%e0%b8%84%e0%b8%a3%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%88%e0%b8%b3%e0%b8%ab\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.dent.psu.ac.th\/dent\/%e0%b8%82%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b9%80%e0%b8%a7%e0%b8%a5%e0%b8%b2%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%aa%e0%b8%a1%e0%b8%b1%e0%b8%84%e0%b8%a3%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%88%e0%b8%b3%e0%b8%ab\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.dent.psu.ac.th\/dent\/"},{"@type":"ListItem","position":2,"name":"\u0e02\u0e22\u0e32\u0e22\u0e40\u0e27\u0e25\u0e32\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e42\u0e23\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e0a\u0e31\u0e49\u0e19 G \u0e2d\u0e32\u0e04\u0e32\u0e23 1\u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2569"}]},{"@type":"WebSite","@id":"https:\/\/www.dent.psu.ac.th\/dent\/#website","url":"https:\/\/www.dent.psu.ac.th\/dent\/","name":"\u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c","description":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c","publisher":{"@id":"https:\/\/www.dent.psu.ac.th\/dent\/#organization"},"alternateName":"Dent PSU","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dent.psu.ac.th\/dent\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/www.dent.psu.ac.th\/dent\/#organization","name":"\u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c","alternateName":"Dent PSU","url":"https:\/\/www.dent.psu.ac.th\/dent\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.dent.psu.ac.th\/dent\/#\/schema\/logo\/image\/","url":"https:\/\/www.dent.psu.ac.th\/dent\/wp-content\/uploads\/2020\/09\/logo_short_v_en.png","contentUrl":"https:\/\/www.dent.psu.ac.th\/dent\/wp-content\/uploads\/2020\/09\/logo_short_v_en.png","width":960,"height":800,"caption":"\u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c"},"image":{"@id":"https:\/\/www.dent.psu.ac.th\/dent\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DentPSU\/"]},{"@type":"Person","@id":"https:\/\/www.dent.psu.ac.th\/dent\/#\/schema\/person\/069e8a0892876674876f8ba63c466988","name":"Jaruwan damsyum","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.dent.psu.ac.th\/dent\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/208d4c5a44e4da86a40f61d8dfa10656?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/208d4c5a44e4da86a40f61d8dfa10656?s=96&d=mm&r=g","caption":"Jaruwan damsyum"},"url":"https:\/\/www.dent.psu.ac.th\/dent\/author\/jaruwan-d\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/www.dent.psu.ac.th\/dent\/wp-content\/uploads\/2026\/05\/\u0e02\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e15\u0e25\u0e32\u0e14\u0e1e\u0e31\u0e2a\u0e14\u0e38\u0e38-2.jpg",2160,1080,false],"thumbnail":["https:\/\/www.dent.psu.ac.th\/dent\/wp-content\/uploads\/2026\/05\/\u0e02\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e15\u0e25\u0e32\u0e14\u0e1e\u0e31\u0e2a\u0e14\u0e38\u0e38-2-100x100.jpg",100,100,true],"medium":["https:\/\/www.dent.psu.ac.th\/dent\/wp-content\/uploads\/2026\/05\/\u0e02\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e15\u0e25\u0e32\u0e14\u0e1e\u0e31\u0e2a\u0e14\u0e38\u0e38-2.jpg",2160,1080,false],"medium_large":["https:\/\/www.dent.psu.ac.th\/dent\/wp-content\/uploads\/2026\/05\/\u0e02\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e15\u0e25\u0e32\u0e14\u0e1e\u0e31\u0e2a\u0e14\u0e38\u0e38-2-768x384.jpg",640,320,true],"large":["https:\/\/www.dent.psu.ac.th\/dent\/wp-content\/uploads\/2026\/05\/\u0e02\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e15\u0e25\u0e32\u0e14\u0e1e\u0e31\u0e2a\u0e14\u0e38\u0e38-2.jpg",2160,1080,false],"1536x1536":["https:\/\/www.dent.psu.ac.th\/dent\/wp-content\/uploads\/2026\/05\/\u0e02\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e15\u0e25\u0e32\u0e14\u0e1e\u0e31\u0e2a\u0e14\u0e38\u0e38-2-1536x768.jpg",1536,768,true],"2048x2048":["https:\/\/www.dent.psu.ac.th\/dent\/wp-content\/uploads\/2026\/05\/\u0e02\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e15\u0e25\u0e32\u0e14\u0e1e\u0e31\u0e2a\u0e14\u0e38\u0e38-2-2048x1024.jpg",2048,1024,true]},"uagb_author_info":{"display_name":"Jaruwan damsyum","author_link":"https:\/\/www.dent.psu.ac.th\/dent\/author\/jaruwan-d\/"},"uagb_comment_info":0,"uagb_excerpt":"\u0e14\u0e49\u0e27\u0e22\u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e23&hellip;","publishpress_future_action":{"enabled":false,"date":"2026-07-22 12:58:33","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"_links":{"self":[{"href":"https:\/\/www.dent.psu.ac.th\/dent\/wp-json\/wp\/v2\/posts\/10979"}],"collection":[{"href":"https:\/\/www.dent.psu.ac.th\/dent\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dent.psu.ac.th\/dent\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dent.psu.ac.th\/dent\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dent.psu.ac.th\/dent\/wp-json\/wp\/v2\/comments?post=10979"}],"version-history":[{"count":2,"href":"https:\/\/www.dent.psu.ac.th\/dent\/wp-json\/wp\/v2\/posts\/10979\/revisions"}],"predecessor-version":[{"id":10983,"href":"https:\/\/www.dent.psu.ac.th\/dent\/wp-json\/wp\/v2\/posts\/10979\/revisions\/10983"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dent.psu.ac.th\/dent\/wp-json\/wp\/v2\/media\/10980"}],"wp:attachment":[{"href":"https:\/\/www.dent.psu.ac.th\/dent\/wp-json\/wp\/v2\/media?parent=10979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dent.psu.ac.th\/dent\/wp-json\/wp\/v2\/categories?post=10979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dent.psu.ac.th\/dent\/wp-json\/wp\/v2\/tags?post=10979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}